{"id":26102,"date":"2015-11-20T10:20:55","date_gmt":"2015-11-20T10:20:55","guid":{"rendered":"https:\/\/www.brandwatch.com\/es\/?p=26102"},"modified":"2024-09-11T10:45:06","modified_gmt":"2024-09-11T10:45:06","slug":"justino","status":"publish","type":"post","link":"https:\/\/www.brandwatch.com\/es\/blog\/justino\/","title":{"rendered":"#Justino &#8211; la entra\u00f1able campa\u00f1a de Loter\u00eda de Navidad"},"content":{"rendered":"<p>La Navidad despierta en la mayor\u00eda de las personas que la celebran una gran variedad de sentimientos. En muchos amor y alegr\u00eda, en otros melancol\u00eda, y en otros tantos la Navidad despierta la necesidad de adquirir productos y\/o servicios, ya sea para su consumo propio o bien para regal\u00e1rselos a nuestros seres m\u00e1s queridos.<!--more--><\/p>\n<p>Este fen\u00f3meno no es ninguna novedad para los departamentos de marketing y desde hace mucho tiempo las empresas crean campa\u00f1as de Navidad aprovechando esta predisposici\u00f3n a la compra.<\/p>\n<p>Algunas empresas han realizado esta tarea con tal excelencia que hoy en d\u00eda todo el mundo espera ver los anuncios que a\u00f1o tras a\u00f1o lanzan en esta \u00e9poca.<\/p>\n<p><a href=\"https:\/\/www.brandwatch.com\/es\/2014\/12\/analizamos-la-repercusion-del-ultimo-anuncio-de-freixenet-en-las-redes-sociales-minuto-minuto\/\" target=\"_blank\" rel=\"noopener\">Freixenet<\/a>, <a href=\"https:\/\/www.youtube.com\/watch?v=0VIStKrCBHQ\" target=\"_blank\" rel=\"noopener\">Airtel<\/a> y <a href=\"https:\/\/www.youtube.com\/watch?v=BR6WfTlKt30\" target=\"_blank\" rel=\"noopener\">El Almendro<\/a> son algunas de las marcas que han conseguido crear anuncios entra\u00f1ables que todo el mundo recuerda, y entre ellas no puede faltar el anuncio de la Loter\u00eda de Navidad.<\/p>\n<hr \/>\n<h3>#Justino y la Loter\u00eda de Navidad 2015<\/h3>\n<p>&nbsp;<\/p>\n<p>Comprar un d\u00e9cimo de loter\u00eda de Navidad se ha convertido en una tradici\u00f3n tan arraigada en Espa\u00f1a, que Loter\u00edas y Apuestas del Estado pr\u00e1cticamente no necesitar\u00eda realizar ning\u00fan esfuerzo para estimular la compra de boletos.<\/p>\n<p>Sin embargo, sus anuncios tienen tanta acogida que se podr\u00eda decir que esta entidad est\u00e1 pr\u00e1cticamente obligada a realizar un spot, a poder ser, mejor cada a\u00f1o.<\/p>\n<p><a href=\"http:\/\/www.leoburnett.es\/\" target=\"_blank\" rel=\"noopener\">Leo Burnett<\/a> ha sido la agencia encargada de realizar por segundo a\u00f1o consecutivo esta tarea. Despu\u00e9s de deleitarnos con su galardonada campa\u00f1a del 2014, el list\u00f3n estaba muy alto.<\/p>\n<p>\u00bfQu\u00e9 reacciones se han generado en las redes sociales tras el lanzamiento de su nueva campa\u00f1a de navidad, #Justino, el pasado 16 de noviembre?<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/tY3vQTrCn7I\" width=\"100%\" height=\"315\" frameborder=\"0\"><\/iframe><\/p>\n<hr \/>\n<p>El mismo d\u00eda de su lanzamiento, hubo m\u00e1s de 10 000 menciones directas sobre el anuncio, mayoritariamente en Twitter (86 %) y en Facebook (13 %). Por el momento ese n\u00famero ya se ha duplicado y seguramente siga creciendo hasta pasado el sorteo.<\/p>\n<p><a href=\"https:\/\/www.brandwatch.com\/es\/wp-content\/uploads\/2015\/11\/01-Loter\u00eda-Navidad.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-26104 size-full\" src=\"https:\/\/www.brandwatch.com\/es\/wp-content\/uploads\/2015\/11\/01-Loter\u00eda-Navidad.png\" alt=\"01 Loter\u00eda Navidad\" width=\"856\" height=\"483\" \/><\/a><\/p>\n<p>En t\u00e9rminos potenciales, estas 10 792 menciones sobre el anuncio de #Justino alcanzaron a m\u00e1s de 60 millones de usuarios en Twitter el mismo 16 de noviembre.<\/p>\n<p>Como sabemos, dentro de estas conversaciones hay autores a los que les ha gustado el anuncio y a los que no. Analizar el sentimiento de m\u00e1s de diez mil menciones no es una tarea f\u00e1cil, por lo que se necesita una herramienta potente que nos facilite el trabajo.<\/p>\n<p>Brandwatch Analytics nos ofrece diferentes posibilidades para realizar dicho an\u00e1lisis: el sentimiento se puede analizar de forma manual, automatizada con reglas o bien usando el Natural Language Processing que nuestra plataforma tiene integrado de serie.<\/p>\n<p>Si bien el an\u00e1lisis manual de las menciones ser\u00eda la metodolog\u00eda m\u00e1s precisa, nos llevar\u00eda demasiado tiempo, por lo que en este caso hemos utilizado una de las herramientas de Brandwatch Analytics, las Bulk Actions, para tomar una muestra aleatoria.<\/p>\n<p>La plataforma tom\u00f3 una muestra de 370 menciones y seguidamente les otorgamos el sentimiento manualmente a cada una de \u00e9stas dependiendo de qu\u00e9 tono utilizaron los autores al hablar del anuncio.<\/p>\n<p>Extrapolando los resultados al resto de la poblaci\u00f3n (menciones, en este caso), podemos afirmar que, con un nivel de confianza del 95%, el sentimiento generado en las redes sociales hacia el anuncio es el siguiente:<\/p>\n<p><a href=\"https:\/\/www.brandwatch.com\/es\/wp-content\/uploads\/2015\/11\/02-Loter\u00eda-Navidad.png\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-26105 size-full aligncenter\" src=\"https:\/\/www.brandwatch.com\/es\/wp-content\/uploads\/2015\/11\/02-Loter\u00eda-Navidad.png\" alt=\"02 Loter\u00eda Navidad\" width=\"1014\" height=\"454\" \/><\/a><\/p>\n<p>#Justino tuvo definitivamente una genial acogida en las redes sociales. Varios influenciadores potenciales, como periodistas o cantantes, tambi\u00e9n expresaron su opini\u00f3n sobre el anuncio, multiplicando su\u00a0alcance:<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"es\" dir=\"ltr\"><a href=\"https:\/\/t.co\/DPQrbFgjBo\">https:\/\/t.co\/DPQrbFgjBo<\/a><br \/>Qu\u00e9 bonito cuando la gente se esfuerza en utilizar su mente xa emocionar a los dem\u00e1s con un espiritu solidario\u2764<br \/>\ud83d\udc4f\ud83c\udffc\ud83d\ude4c\ud83c\udffc<\/p>\n<p>&mdash; Vega (@VEGAOFICIAL) <a href=\"https:\/\/twitter.com\/VEGAOFICIAL\/status\/666380572151926784?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">November 16, 2015<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<hr \/>\n<h3>Las emociones perduran m\u00e1s que los memes<\/h3>\n<p>&nbsp;<\/p>\n<p>Todo \u00e9xito genera tambi\u00e9n cr\u00edticas. Los memes no han parado de surgir desde el lanzamiento del anuncio, comparando el protagonista con Super Mario (Nintendo), entre otros.<\/p>\n<p>Leo Burnett tambi\u00e9n consigui\u00f3 generar cr\u00edticas entre el p\u00fablico por haber encargado la realizaci\u00f3n de este anuncio a un estudio sueco en lugar de a uno espa\u00f1ol, teniendo en cuenta la situaci\u00f3n de desempleo del pa\u00eds.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"es\" dir=\"ltr\">Lamentamos enormemente que la animaci\u00f3n del anuncio de la loter\u00eda (<a href=\"https:\/\/twitter.com\/hashtag\/Justino?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#Justino<\/a>) no se hiciera en Espa\u00f1a. Aqu\u00ed hay magn\u00edficos profesionales<\/p>\n<p>&mdash; DIGITALL (@digitallevent) <a href=\"https:\/\/twitter.com\/digitallevent\/status\/666334322257973248?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">November 16, 2015<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Pero \u00bfqu\u00e9 porci\u00f3n de las conversaciones representan estos temas? Utilizando reglas autom\u00e1ticas hemos categorizado las conversaciones para determinar cu\u00e1l de estos subtemas ha generado m\u00e1s ruido:<\/p>\n<p><a href=\"https:\/\/www.brandwatch.com\/es\/wp-content\/uploads\/2015\/11\/03-Loter\u00eda-Navidad.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-26106 size-full\" src=\"https:\/\/www.brandwatch.com\/es\/wp-content\/uploads\/2015\/11\/03-Loter\u00eda-Navidad.png\" alt=\"03 Loter\u00eda Navidad\" width=\"1079\" height=\"467\" \/><\/a><\/p>\n<p>Las menciones negativas sobre el estudio de animaci\u00f3n que realiz\u00f3 el anuncio ocuparon solamente una peque\u00f1a porci\u00f3n de las conversaciones (1 %) durante el periodo analizado.<\/p>\n<p>Los memes adquirieron gran popularidad el d\u00eda del lanzamiento, pero las emociones que genera el anuncio en el p\u00fablico son claramente el tema que m\u00e1s se ha mencionado de estos tres, como podemos observar en el gr\u00e1fico sobre estas l\u00edneas.<\/p>\n<p>Este clip ha conseguido que mucha gente comente abiertamente que se le han saltado las l\u00e1grimas:<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"es\" dir=\"ltr\">Llorando a moco tendido con el anuncio de la loteria de Navidad <a href=\"https:\/\/twitter.com\/hashtag\/FaPlorar?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#FaPlorar<\/a><\/p>\n<p>&mdash; Laura Fa (@Laura__Fa) <a href=\"https:\/\/twitter.com\/Laura__Fa\/status\/666734659460595712?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">November 17, 2015<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Existen muchos otros insights interesantes que podr\u00edamos obtener de estos datos. Por ejemplo, ser\u00eda interesante comparar el n\u00famero de menciones generadas este a\u00f1o con las del a\u00f1o pasado.<\/p>\n<p>El siguiente gr\u00e1fico muestra los vol\u00famenes de las dos campa\u00f1as. \u00bfTe gustar\u00eda saber cu\u00e1l de las dos es la l\u00ednea azul? Pide una demo gratuita de Brandwatch ahora y estaremos encantados de mostr\u00e1rtelo.<\/p>\n<p><a href=\"https:\/\/www.brandwatch.com\/es\/wp-content\/uploads\/2015\/11\/04-Loter\u00eda-Navidad.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-26107 size-full\" src=\"https:\/\/www.brandwatch.com\/es\/wp-content\/uploads\/2015\/11\/04-Loter\u00eda-Navidad.png\" alt=\"04 Loter\u00eda Navidad\" width=\"758\" height=\"373\" \/><\/a><\/p>\n<p>[bw_banner_cta url=&#8221;https:\/\/www.brandwatch.com\/es\/demo\/&#8221; button=&#8221;PIDE TU DEMO&#8221; type=2 title=&#8221;Brandwatch Analytics&#8221;]Descubre todo lo que nuestra plataforma puede hacer por tu marca.[\/bw_banner_cta]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Navidad despierta en la mayor\u00eda de las personas que la celebran una gran variedad de sentimientos. En muchos amor y alegr\u00eda, en otros melancol\u00eda, y en otros tantos la Navidad despierta la necesidad de adquirir productos y\/o servicios, ya sea para su consumo propio o bien para regal\u00e1rselos a nuestros seres m\u00e1s queridos.<\/p>\n","protected":false},"author":164,"featured_media":26110,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false},"categories":[42,139,519],"tags":[735,737,625,738,736,382,473],"class_list":["post-26102","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-research","category-monitoring","category-tendencias","tag-justino","tag-anuncio","tag-campana-de-publicidad","tag-comercial","tag-loteria-de-navidad","tag-monitorizacion","tag-navidad"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.brandwatch.com\/es\/wp-json\/wp\/v2\/posts\/26102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brandwatch.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brandwatch.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brandwatch.com\/es\/wp-json\/wp\/v2\/users\/164"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brandwatch.com\/es\/wp-json\/wp\/v2\/comments?post=26102"}],"version-history":[{"count":0,"href":"https:\/\/www.brandwatch.com\/es\/wp-json\/wp\/v2\/posts\/26102\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brandwatch.com\/es\/wp-json\/wp\/v2\/media\/26110"}],"wp:attachment":[{"href":"https:\/\/www.brandwatch.com\/es\/wp-json\/wp\/v2\/media?parent=26102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brandwatch.com\/es\/wp-json\/wp\/v2\/categories?post=26102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brandwatch.com\/es\/wp-json\/wp\/v2\/tags?post=26102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}